{"id":35239,"date":"2025-05-06T10:49:08","date_gmt":"2025-05-06T10:49:08","guid":{"rendered":"https:\/\/ati.novanta.com\/product\/tool-changers-mc-50\/"},"modified":"2026-01-31T18:50:55","modified_gmt":"2026-01-31T18:50:55","slug":"tool-changers-mc-50","status":"publish","type":"product","link":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/","title":{"rendered":"Troca manual de ferramentas MC-50"},"content":{"rendered":"\n<div class=\"alignfull has-secondary-background-color has-background is-layout-constrained wp-block-one-novanta-section-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-one-novanta-section-content alignwide\">\n<rt-tabs class=\"novanta-tabs-wrapper\" current-tab=\"tab-recursos-do-produto-1\" >\n\n\t<rt-tabs-nav class=\"novanta-tabs-nav\">\n\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\"  active=\"yes\">\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-recursos-do-produto-1\">Recursos do produto<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\" >\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-especificacoes-2\">Especifica\u00e7\u00f5es<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\" >\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-documentos-e-downloads-3\">Documentos e downloads<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\" >\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-modelos-cad-3d-4\">modelos CAD 3D<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\" >\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-acessorios-5\">Acess\u00f3rios<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t\t\t\t\t\t<rt-tabs-nav-item class=\"novanta-tabs-nav__item has-medium-font-size\" >\n\t\t\t\t<a class=\"has-foreground-color\" href=\"#tab-grafico-de-carga-util-6\">Gr\u00e1fico de carga \u00fatil<\/a>\n\t\t\t<\/rt-tabs-nav-item>\n\n\t\t\t\t\t\t<\/rt-tabs-nav>\n\n\t\t\t\t\t<rt-tabs-tab id=\"tab-recursos-do-produto-1\"  open=\"yes\">\n\t\t\t\t\t\n<div class=\"alignfull is-layout-constrained wp-block-one-novanta-section-is-layout-constrained\" style=\"padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-one-novanta-section-content alignwide\">\n<div class=\"two-columns--media-align-left wp-block-one-novanta-fifty-fifty-wrapper two-columns two-columns--vertical-align-top\">\n\t\n<div class=\"two-columns__column\">\n\t<h2 class=\"one-novanta-50-50-wrapper__heading has-xx-large-font-size\">Recursos do produto<\/h2><\/div>\n\n<div class=\"two-columns__column\">\n\t\n<div class=\"wp-block-one-novanta-fifty-fifty-wrapper alignfull\">\n<ul class=\"wp-block-list\">\n<li>(4) Portas de passagem de ar integradas M5 ou #10-32 em um pacote compacto de 572 gramas<\/li>\n\n\n\n<li>Troca manual de ferramentas para cobots de at\u00e9 25 kg de carga \u00fatil e rob\u00f4s industriais de at\u00e9 10 kg de carga \u00fatil.<\/li>\n\n\n\n<li>Montagem direta nos pulsos de rob\u00f4s ISO 9409-1-50-4-M6 para minimizar a altura da pilha.<\/li>\n\n\n\n<li>Troca r\u00e1pida de efetores finais com a\u00e7\u00e3o de alavanca; n\u00e3o s\u00e3o necess\u00e1rias ferramentas.<\/li>\n\n\n\n<li>Um (1) plano dispon\u00edvel para montar m\u00f3dulos el\u00e9tricos para aumentar a funcionalidade<\/li>\n\n\n\n<li>O recurso de travamento secund\u00e1rio garante que a alavanca n\u00e3o se solte se ficar presa<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline has-arrow type-light is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/ati.novanta.com\/pt\/products\/tool-changers\/\">Saiba mais sobre Trocas de ferramentas<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\t\t\t\t<rt-tabs-tab id=\"tab-especificacoes-2\" >\n\t\t\t\t\t\n<div class=\"wp-one-novanta-table wp-one-novanta-table--has-background--secondary\">\n\n\t<div class=\"wp-one-novanta-table__header\">\n\t\t\n\t\t<\/div>\n\n\t<figure data-is-loading=\"false\">\n\n\t\t<table class=\"wp-one-novanta-table__wrapper\">\n\n\t\t\t<thead class=\"wp-one-novanta-table__head\">\n\t\t\t\t<tr class=\"wp-one-novanta-table__head-row\">\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Specification<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Value<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\n\t\t\t<tbody class=\"wp-one-novanta-table__body\">\n\t\t\t\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tDist\u00e2ncia m\u00e1xima de travamento\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t1.0 mm\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tTamanhos de porta de passagem\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t(4) M5\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tQuantidade de portas de passagem pneum\u00e1tica\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t4\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tRepetibilidade posicional\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t0.0102 mm\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tLimite de carga \u00fatil sugerido\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t30 kg\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tCapacidade de momento est\u00e1tico X\/Y\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t25 Nm\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tZ Capacidade de momento est\u00e1tico\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t25 Nm\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tPeso do lado mestre\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t0.386 kg\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tPeso do lado da ferramenta\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t0.186 kg\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tPeso quando acoplado\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t0.572 kg\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tTipo de acionamento\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tManual\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tTipo de pulso do rob\u00f4\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tPadr\u00e3o\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tCor\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tPreto\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tFios de porta\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tRoscas M5\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\t\t\t<\/tbody>\n\n\t\t<\/table>\n\n\t\t\n\t<div class=\"\n\t\twp-one-novanta-table__is-loading hidden\t\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 24 24\"><!-- Icon from SVG Spinners by Utkarsh Verma - https:\/\/github.com\/n3r4zzurr0\/svg-spinners\/blob\/main\/LICENSE --><path fill=\"currentColor\" d=\"M12,1A11,11,0,1,0,23,12,11,11,0,0,0,12,1Zm0,19a8,8,0,1,1,8-8A8,8,0,0,1,12,20Z\" opacity=\".25\" \/><path fill=\"currentColor\" d=\"M12,4a8,8,0,0,1,7.89,6.7A1.53,1.53,0,0,0,21.38,12h0a1.5,1.5,0,0,0,1.48-1.75,11,11,0,0,0-21.72,0A1.5,1.5,0,0,0,2.62,12h0a1.53,1.53,0,0,0,1.49-1.3A8,8,0,0,1,12,4Z\"><animateTransform attributeName=\"transform\" dur=\"0.75s\" repeatCount=\"indefinite\" type=\"rotate\" values=\"0 12 12;360 12 12\" \/><\/path><\/svg>\n\t<\/div>\n\n\t<\/figure>\n\n\t\n<\/div>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\t\t\t\t<rt-tabs-tab id=\"tab-documentos-e-downloads-3\" >\n\t\t\t\t\t\n<div class=\"align wp-block-one-novanta-documents wp-one-novanta-table wp-one-novanta-table--has-background--secondary\">\n\n\t<div class=\"wp-one-novanta-table__header\">\n\t\t\n\t\n<div class=\"wp-one-novanta-table__filter one-novanta-filter-dropdown\" data-filter-column=\"2\">\n\n\t\t<button class=\"one-novanta-filter-dropdown__button wp-one-novanta-button wp-one-novanta-button--secondary\" aria-expanded=\"false\" type=\"button\">\n\t\t<span class=\"text\"><span class=\"one-novanta-filter-dropdown__selected\"><span class=\"has-medium-font-size one-novanta-filter-dropdown__selected-value-prefix\"><\/span><span class=\"has-medium-font-size one-novanta-filter-dropdown__selected-value\">Filtrar por Tipo<\/span><\/span><\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"8\" viewBox=\"0 0 12 8\" fill=\"none\"><path fill=\"currentColor\" d=\"M1.41.297 6 4.877l4.59-4.58L12 1.707l-6 6-6-6L1.41.297Z\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t\n\t<ul class=\"one-novanta-filter-dropdown__dropdown-list is-hidden one-novanta-filter-dropdown__dropdown-list--left\" role=\"listbox\">\n\t\t<!-- Default option -->\n\t\t<li id=\"filter-option-0\" role=\"option\" class=\"selected wp-one-novanta-table__filter__option--default\">Filtrar por Tipo<\/li>\n\n\t\t<!-- Options from column. -->\n\t\t\t\t\t<li id=\"filter-option-1\" role=\"option\">Desenhos<\/li>\n\t\t\t\t\t\t<li id=\"filter-option-2\" role=\"option\">Manuais<\/li>\n\t\t\t\t<\/ul>\n<\/div>\n\t<\/div>\n\n\t<figure data-is-loading=\"false\">\n\n\t\t<table class=\"wp-one-novanta-table__wrapper\">\n\n\t\t\t<thead class=\"wp-one-novanta-table__head\">\n\t\t\t\t<tr class=\"wp-one-novanta-table__head-row\">\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Baixar<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Tipo de download<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Idioma<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\n\t\t\t<tbody class=\"wp-one-novanta-table__body\">\n\t\t\t\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tDesenho do trocador manual de ferramentas MC-50\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tDesenhos\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t<a href=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9630-20-MC050.auto.pdf\" target=\"_blank\">English<\/a>\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tManual do trocador de ferramentas MC-50\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tManuais\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t<a href=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9620-20-B-MC-50.pdf\" target=\"_blank\">English<\/a>\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tbody>\n\n\t\t<\/table>\n\n\t\t\n\t<div class=\"\n\t\twp-one-novanta-table__is-loading hidden\t\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 24 24\"><!-- Icon from SVG Spinners by Utkarsh Verma - https:\/\/github.com\/n3r4zzurr0\/svg-spinners\/blob\/main\/LICENSE --><path fill=\"currentColor\" d=\"M12,1A11,11,0,1,0,23,12,11,11,0,0,0,12,1Zm0,19a8,8,0,1,1,8-8A8,8,0,0,1,12,20Z\" opacity=\".25\" \/><path fill=\"currentColor\" d=\"M12,4a8,8,0,0,1,7.89,6.7A1.53,1.53,0,0,0,21.38,12h0a1.5,1.5,0,0,0,1.48-1.75,11,11,0,0,0-21.72,0A1.5,1.5,0,0,0,2.62,12h0a1.53,1.53,0,0,0,1.49-1.3A8,8,0,0,1,12,4Z\"><animateTransform attributeName=\"transform\" dur=\"0.75s\" repeatCount=\"indefinite\" type=\"rotate\" values=\"0 12 12;360 12 12\" \/><\/path><\/svg>\n\t<\/div>\n\n\t<\/figure>\n\n\t\n<\/div>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\t\t\t\t<rt-tabs-tab id=\"tab-modelos-cad-3d-4\" >\n\t\t\t\t\t\n<div class=\"wp-one-novanta-table wp-one-novanta-table--has-background--secondary\">\n\n\t<div class=\"wp-one-novanta-table__header\">\n\t\t\n\t\t<\/div>\n\n\t<figure data-is-loading=\"false\">\n\n\t\t<table class=\"wp-one-novanta-table__wrapper\">\n\n\t\t\t<thead class=\"wp-one-novanta-table__head\">\n\t\t\t\t<tr class=\"wp-one-novanta-table__head-row\">\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Baixar<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-table__head-cell wp-one-novanta-table__head-cell__background-mid-gray\">Descri\u00e7\u00e3o<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\n\t\t\t<tbody class=\"wp-one-novanta-table__body\">\n\t\t\t\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t<a href='https:\/\/www.3dcontentcentral.com\/Model-Preview-Resp.aspx?catalogId=201&amp;name=9122-050T-000' target='_blank'>9122-050T-000<\/a>\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tMC-50 Troca manual de ferramentas, lado da ferramenta\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\n\n<tr class=\"wp-one-novanta-table__body-row\">\n\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\t<a href='https:\/\/www.3dcontentcentral.com\/Model-Preview-Resp.aspx?catalogId=201&amp;name=9122-050M-000' target='_blank'>9122-050M-000<\/a>\t\t\t<\/td>\n\t\t\t\t\t\t\t<td class=\"wp-one-novanta-table__body-cell\">\n\t\t\t\tMC-50 Troca manual de ferramentas, lado mestre\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\n\t\t\t<\/tbody>\n\n\t\t<\/table>\n\n\t\t\n\t<div class=\"\n\t\twp-one-novanta-table__is-loading hidden\t\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 24 24\"><!-- Icon from SVG Spinners by Utkarsh Verma - https:\/\/github.com\/n3r4zzurr0\/svg-spinners\/blob\/main\/LICENSE --><path fill=\"currentColor\" d=\"M12,1A11,11,0,1,0,23,12,11,11,0,0,0,12,1Zm0,19a8,8,0,1,1,8-8A8,8,0,0,1,12,20Z\" opacity=\".25\" \/><path fill=\"currentColor\" d=\"M12,4a8,8,0,0,1,7.89,6.7A1.53,1.53,0,0,0,21.38,12h0a1.5,1.5,0,0,0,1.48-1.75,11,11,0,0,0-21.72,0A1.5,1.5,0,0,0,2.62,12h0a1.53,1.53,0,0,0,1.49-1.3A8,8,0,0,1,12,4Z\"><animateTransform attributeName=\"transform\" dur=\"0.75s\" repeatCount=\"indefinite\" type=\"rotate\" values=\"0 12 12;360 12 12\" \/><\/path><\/svg>\n\t<\/div>\n\n\t<\/figure>\n\n\t\n<\/div>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\t\t\t\t<rt-tabs-tab id=\"tab-acessorios-5\" >\n\t\t\t\t\t\n<div class=\"align wp-block-one-novanta-accessories wp-one-novanta-compare-model-table wp-one-novanta-compare-model-table--variant--accessories\">\n\n\t\n<div class=\"wp-one-novanta-compare-model-table__filter one-novanta-filter-dropdown\" data-filter-column=\"1\">\n\n\t\t<button class=\"one-novanta-filter-dropdown__button wp-one-novanta-button wp-one-novanta-button--secondary\" aria-expanded=\"false\" type=\"button\">\n\t\t<span class=\"text\"><span class=\"one-novanta-filter-dropdown__selected\"><span class=\"has-medium-font-size one-novanta-filter-dropdown__selected-value-prefix\"><\/span><span class=\"has-medium-font-size one-novanta-filter-dropdown__selected-value\">Filtrar por N\u00famero da pe\u00e7a<\/span><\/span><\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"8\" viewBox=\"0 0 12 8\" fill=\"none\"><path fill=\"currentColor\" d=\"M1.41.297 6 4.877l4.59-4.58L12 1.707l-6 6-6-6L1.41.297Z\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t\n\t<ul class=\"one-novanta-filter-dropdown__dropdown-list is-hidden one-novanta-filter-dropdown__dropdown-list--left\" role=\"listbox\">\n\t\t<!-- Default option -->\n\t\t<li id=\"filter-option-0\" role=\"option\" class=\"selected wp-one-novanta-compare-model-table__filter__option--default\">Filtrar por N\u00famero da pe\u00e7a<\/li>\n\n\t\t<!-- Options from column. -->\n\t\t\t\t\t<li id=\"filter-option-1\" role=\"option\">9122-050M-IP-11858<\/li>\n\t\t\t\t\t\t<li id=\"filter-option-2\" role=\"option\">9005-20-9217<\/li>\n\t\t\t\t\t\t<li id=\"filter-option-3\" role=\"option\">9005-20-9115<\/li>\n\t\t\t\t\t\t<li id=\"filter-option-4\" role=\"option\">9005-20-9112<\/li>\n\t\t\t\t\t\t<li id=\"filter-option-5\" role=\"option\">JJ112<\/li>\n\t\t\t\t<\/ul>\n<\/div>\n\n\t<table class=\"wp-one-novanta-compare-model-table__wrapper\">\n\n\t\t<thead class=\"wp-one-novanta-compare-model-table__head\">\n\t\t\t<tr class=\"wp-one-novanta-compare-model-table__head-row\">\n\t\t\t\t<th class=\"wp-one-novanta-compare-model-table__head-cell wp-one-novanta-compare-model-table__head-image\"><\/th>\n\n\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-compare-model-table__head-cell\">N\u00famero da pe\u00e7a<\/th>\n\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-compare-model-table__head-cell\">Descri\u00e7\u00e3o<\/th>\n\t\t\t\t\t\t\t\t\t<th class=\"wp-one-novanta-compare-model-table__head-cell\"><\/th>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/tr>\n\t\t<\/thead>\n\n\t\t<tbody class=\"wp-one-novanta-compare-model-table__body\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t<tr class=\"wp-one-novanta-compare-model-table__body-row\">\n\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9122-050M-IP-11858.jpg?quality=85&amp;strip=all&amp;w=180\" class=\"attachment-180x180 size-180x180\" alt=\"Montagem da placa de interface\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9122-050M-IP-11858.jpg?resize=320%2C320&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9122-050M-IP-11858.jpg?resize=400%2C400&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"N\u00famero da pe\u00e7a\">\n\t\t\t\t\t\t\t9122-050M-IP-11858\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"Descri\u00e7\u00e3o\">\n\t\t\t\t\t\t\tKit IP para MC-50M a BC 80, (6) M8, Boss 50, D8\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"\">\n\t\t\t\t\t\t\t\n<ati-add-to-cart-button data-product-id=\"34099\" data-variation-id=\"0\" data-text=\"Adicionar \u00e0 cota\u00e7\u00e3o\" data-added-text=\"Adicionado \u00e0 cita\u00e7\u00e3o\" data-failed-text=\"Falha\" class=\"\">\n\t\t<button class=\"one-novanta-add-to-cart-button wp-one-novanta-button wp-one-novanta-button--primary\" type=\"button\">\n\t\t<span class=\"text\">Adicionar \u00e0 cota\u00e7\u00e3o<\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 10.59 4.58 6 0 1.41 1.41 0l6 6-6 6L0 10.59z\" fill=\"currentColor\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t<\/ati-add-to-cart-button>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\n\t\t\t\t<tr class=\"wp-one-novanta-compare-model-table__body-row\">\n\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9217.jpg?quality=85&amp;strip=all&amp;w=180\" class=\"attachment-180x180 size-180x180\" alt=\"Kit de placa de identifica\u00e7\u00e3o\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9217.jpg?resize=320%2C320&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9217.jpg?resize=400%2C400&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"N\u00famero da pe\u00e7a\">\n\t\t\t\t\t\t\t9005-20-9217\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"Descri\u00e7\u00e3o\">\n\t\t\t\t\t\t\tKit de placa de press\u00e3o, di\u00e2metro externo de 25 mm, para QC com rebaixo de placa de press\u00e3o de 16 mm, fixa\u00e7\u00e3o \u00fanica M3 SHCS\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"\">\n\t\t\t\t\t\t\t\n<ati-add-to-cart-button data-product-id=\"34100\" data-variation-id=\"0\" data-text=\"Adicionar \u00e0 cota\u00e7\u00e3o\" data-added-text=\"Adicionado \u00e0 cita\u00e7\u00e3o\" data-failed-text=\"Falha\" class=\"\">\n\t\t<button class=\"one-novanta-add-to-cart-button wp-one-novanta-button wp-one-novanta-button--primary\" type=\"button\">\n\t\t<span class=\"text\">Adicionar \u00e0 cota\u00e7\u00e3o<\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 10.59 4.58 6 0 1.41 1.41 0l6 6-6 6L0 10.59z\" fill=\"currentColor\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t<\/ati-add-to-cart-button>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\n\t\t\t\t<tr class=\"wp-one-novanta-compare-model-table__body-row\">\n\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9115-1.jpg?quality=85&amp;strip=all&amp;w=180\" class=\"attachment-180x180 size-180x180\" alt=\"\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9115-1.jpg?resize=320%2C320&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9115-1.jpg?resize=400%2C400&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"N\u00famero da pe\u00e7a\">\n\t\t\t\t\t\t\t9005-20-9115\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"Descri\u00e7\u00e3o\">\n\t\t\t\t\t\t\t<p>Kit de conex\u00f5es, (2) conex\u00f5es retas (tubo M5 macho x 4 mm)<\/p>\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"\">\n\t\t\t\t\t\t\t\n<ati-add-to-cart-button data-product-id=\"34118\" data-variation-id=\"0\" data-text=\"Adicionar \u00e0 cota\u00e7\u00e3o\" data-added-text=\"Adicionado \u00e0 cita\u00e7\u00e3o\" data-failed-text=\"Falha\" class=\"\">\n\t\t<button class=\"one-novanta-add-to-cart-button wp-one-novanta-button wp-one-novanta-button--primary\" type=\"button\">\n\t\t<span class=\"text\">Adicionar \u00e0 cota\u00e7\u00e3o<\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 10.59 4.58 6 0 1.41 1.41 0l6 6-6 6L0 10.59z\" fill=\"currentColor\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t<\/ati-add-to-cart-button>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\n\t\t\t\t<tr class=\"wp-one-novanta-compare-model-table__body-row\">\n\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9112.jpg?quality=85&amp;strip=all&amp;w=180\" class=\"attachment-180x180 size-180x180\" alt=\"\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9112.jpg?resize=320%2C320&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/9005-20-9112.jpg?resize=400%2C400&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"N\u00famero da pe\u00e7a\">\n\t\t\t\t\t\t\t9005-20-9112\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"Descri\u00e7\u00e3o\">\n\t\t\t\t\t\t\t<p>Kit de conex\u00f5es, (2) conex\u00f5es de cotovelo girat\u00f3rio (tubo M5 macho x 4 mm)<\/p>\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"\">\n\t\t\t\t\t\t\t\n<ati-add-to-cart-button data-product-id=\"34120\" data-variation-id=\"0\" data-text=\"Adicionar \u00e0 cota\u00e7\u00e3o\" data-added-text=\"Adicionado \u00e0 cita\u00e7\u00e3o\" data-failed-text=\"Falha\" class=\"\">\n\t\t<button class=\"one-novanta-add-to-cart-button wp-one-novanta-button wp-one-novanta-button--primary\" type=\"button\">\n\t\t<span class=\"text\">Adicionar \u00e0 cota\u00e7\u00e3o<\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 10.59 4.58 6 0 1.41 1.41 0l6 6-6 6L0 10.59z\" fill=\"currentColor\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t<\/ati-add-to-cart-button>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\n\t\t\t\t<tr class=\"wp-one-novanta-compare-model-table__body-row\">\n\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/JJ112.jpg?quality=85&amp;strip=all&amp;w=180\" class=\"attachment-180x180 size-180x180\" alt=\"Kit de placa adaptadora\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/JJ112.jpg?resize=320%2C320&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/JJ112.jpg?resize=400%2C400&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/>\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"N\u00famero da pe\u00e7a\">\n\t\t\t\t\t\t\tJJ112\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"Descri\u00e7\u00e3o\">\n\t\t\t\t\t\t\tPlaca adaptadora para o padr\u00e3o da s\u00e9rie K no MC-50.\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"wp-one-novanta-compare-model-table__body-cell wp-one-novanta-compare-model-table__body-content\" data-head=\"\">\n\t\t\t\t\t\t\t\n<ati-add-to-cart-button data-product-id=\"34155\" data-variation-id=\"0\" data-text=\"Adicionar \u00e0 cota\u00e7\u00e3o\" data-added-text=\"Adicionado \u00e0 cita\u00e7\u00e3o\" data-failed-text=\"Falha\" class=\"\">\n\t\t<button class=\"one-novanta-add-to-cart-button wp-one-novanta-button wp-one-novanta-button--primary\" type=\"button\">\n\t\t<span class=\"text\">Adicionar \u00e0 cota\u00e7\u00e3o<\/span>\n\t\t\t\t\t<span class=\"wp-one-novanta-button__icon\">\n\t\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 10.59 4.58 6 0 1.41 1.41 0l6 6-6 6L0 10.59z\" fill=\"currentColor\" \/><\/svg>\t\t\t<\/span>\n\t\t\t<\/button>\n\t<\/ati-add-to-cart-button>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\n\t\t<\/tbody>\n\t<\/table>\n<\/div>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\t\t\t\t<rt-tabs-tab id=\"tab-grafico-de-carga-util-6\" >\n\t\t\t\t\t\n<figure class=\"wp-block-image size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"408\" src=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-mc-50-payload-capacity.jpg\" alt=\"\" class=\"wp-image-46940\" style=\"border-width:1px\" srcset=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-mc-50-payload-capacity.jpg?quality=85&amp;strip=all 569w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-mc-50-payload-capacity.jpg?resize=320%2C229&amp;quality=85&amp;strip=all 320w, https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-mc-50-payload-capacity.jpg?resize=400%2C287&amp;quality=85&amp;strip=all 400w\" sizes=\"auto, (max-width: 569px) 100vw, 569px\" \/><\/figure>\n\t\t\t\t<\/rt-tabs-tab>\n\n\t\t\t\n<\/rt-tabs>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os trocadores manuais de ferramentas da ATI oferecem uma solu\u00e7\u00e3o simples e confi\u00e1vel para a troca r\u00e1pida de efetores sem a necessidade de ferramentas ou energia. Projetados para facilitar o uso e o alinhamento repet\u00edvel, eles reduzem o tempo de inatividade e aumentam a flexibilidade em aplica\u00e7\u00f5es colaborativas, de laborat\u00f3rio ou de baixo volume.<\/p>\n<ul>\n<li>(4) Portas de passagem de ar integradas M5 ou #10-32 em um pacote compacto de 572 gramas<\/li>\n<li>Troca manual de ferramentas para cobots de at\u00e9 25 kg de carga \u00fatil e rob\u00f4s industriais de at\u00e9 10 kg de carga \u00fatil.<\/li>\n<li>Montagem direta nos pulsos de rob\u00f4s ISO 9409-1-50-4-M6 para minimizar a altura da pilha.<\/li>\n<li>Troca r\u00e1pida de efetores finais com a\u00e7\u00e3o de alavanca; n\u00e3o s\u00e3o necess\u00e1rias ferramentas.<\/li>\n<li>Um (1) plano dispon\u00edvel para montar m\u00f3dulos el\u00e9tricos para aumentar a funcionalidade<\/li>\n<\/ul>\n","protected":false},"featured_media":18390,"template":"","meta":{"_acf_changed":false,"is_product_deprecated":false,"new_product_name":"","new_product_url":""},"product_cat":[139,142],"product_tag":[],"class_list":{"0":"post-35239","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tool-changers","7":"product_cat-manual-tool-changers","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Troca manual de ferramentas MC-50 - ATI Industrial Automation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Troca manual de ferramentas MC-50\" \/>\n<meta property=\"og:description\" content=\"Os trocadores manuais de ferramentas da ATI oferecem uma solu\u00e7\u00e3o simples e confi\u00e1vel para a troca r\u00e1pida de efetores sem a necessidade de ferramentas ou energia. Projetados para facilitar o uso e o alinhamento repet\u00edvel, eles reduzem o tempo de inatividade e aumentam a flexibilidade em aplica\u00e7\u00f5es colaborativas, de laborat\u00f3rio ou de baixo volume.  (4) Portas de passagem de ar integradas M5 ou #10-32 em um pacote compacto de 572 gramas Troca manual de ferramentas para cobots de at\u00e9 25 kg de carga \u00fatil e rob\u00f4s industriais de at\u00e9 10 kg de carga \u00fatil. Montagem direta nos pulsos de rob\u00f4s ISO 9409-1-50-4-M6 para minimizar a altura da pilha. Troca r\u00e1pida de efetores finais com a\u00e7\u00e3o de alavanca; n\u00e3o s\u00e3o necess\u00e1rias ferramentas. Um (1) plano dispon\u00edvel para montar m\u00f3dulos el\u00e9tricos para aumentar a funcionalidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/\" \/>\n<meta property=\"og:site_name\" content=\"ATI Industrial Automation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-31T18:50:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/MC-50.jpg?quality=85&strip=all&w=1200&h=675&crop=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/\",\"url\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/\",\"name\":\"Troca manual de ferramentas MC-50 - ATI Industrial Automation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ati.novanta.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/ati-header-image.jpg?quality=85&strip=all\",\"datePublished\":\"2025-05-06T10:49:08+00:00\",\"dateModified\":\"2026-01-31T18:50:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ati.novanta.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/ati-header-image.jpg?quality=85&strip=all\",\"contentUrl\":\"https:\\\/\\\/ati.novanta.com\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/ati-header-image.jpg?quality=85&strip=all\",\"width\":1920,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/product\\\/tool-changers-mc-50\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ati.novanta.com\\\/pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/ati.novanta.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Troca manual de ferramentas MC-50\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#website\",\"url\":\"https:\\\/\\\/ati.novanta.com\\\/\",\"name\":\"ATI Industrial Automation\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ati.novanta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#organization\",\"name\":\"ATI Industrial Automation\",\"url\":\"https:\\\/\\\/ati.novanta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ATI Industrial Automation\"},\"image\":{\"@id\":\"https:\\\/\\\/ati.novanta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Troca manual de ferramentas MC-50 - ATI Industrial Automation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/","og_locale":"pt_BR","og_type":"article","og_title":"Troca manual de ferramentas MC-50","og_description":"Os trocadores manuais de ferramentas da ATI oferecem uma solu\u00e7\u00e3o simples e confi\u00e1vel para a troca r\u00e1pida de efetores sem a necessidade de ferramentas ou energia. Projetados para facilitar o uso e o alinhamento repet\u00edvel, eles reduzem o tempo de inatividade e aumentam a flexibilidade em aplica\u00e7\u00f5es colaborativas, de laborat\u00f3rio ou de baixo volume.  (4) Portas de passagem de ar integradas M5 ou #10-32 em um pacote compacto de 572 gramas Troca manual de ferramentas para cobots de at\u00e9 25 kg de carga \u00fatil e rob\u00f4s industriais de at\u00e9 10 kg de carga \u00fatil. Montagem direta nos pulsos de rob\u00f4s ISO 9409-1-50-4-M6 para minimizar a altura da pilha. Troca r\u00e1pida de efetores finais com a\u00e7\u00e3o de alavanca; n\u00e3o s\u00e3o necess\u00e1rias ferramentas. Um (1) plano dispon\u00edvel para montar m\u00f3dulos el\u00e9tricos para aumentar a funcionalidade","og_url":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/","og_site_name":"ATI Industrial Automation","article_modified_time":"2026-01-31T18:50:55+00:00","og_image":[{"width":1200,"height":640,"url":"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/MC-50.jpg?quality=85&strip=all&w=1200&h=675&crop=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/","url":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/","name":"Troca manual de ferramentas MC-50 - ATI Industrial Automation","isPartOf":{"@id":"https:\/\/ati.novanta.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/#primaryimage"},"image":{"@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/#primaryimage"},"thumbnailUrl":"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-header-image.jpg?quality=85&strip=all","datePublished":"2025-05-06T10:49:08+00:00","dateModified":"2026-01-31T18:50:55+00:00","breadcrumb":{"@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/#primaryimage","url":"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-header-image.jpg?quality=85&strip=all","contentUrl":"https:\/\/ati.novanta.com\/wp-content\/uploads\/sites\/2\/2025\/05\/ati-header-image.jpg?quality=85&strip=all","width":1920,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/ati.novanta.com\/pt\/product\/tool-changers-mc-50\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ati.novanta.com\/pt\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/ati.novanta.com\/products\/"},{"@type":"ListItem","position":3,"name":"Troca manual de ferramentas MC-50"}]},{"@type":"WebSite","@id":"https:\/\/ati.novanta.com\/#website","url":"https:\/\/ati.novanta.com\/","name":"ATI Industrial Automation","description":"","publisher":{"@id":"https:\/\/ati.novanta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ati.novanta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ati.novanta.com\/#organization","name":"ATI Industrial Automation","url":"https:\/\/ati.novanta.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ati.novanta.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ATI Industrial Automation"},"image":{"@id":"https:\/\/ati.novanta.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/product\/35239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/media\/18390"}],"wp:attachment":[{"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/media?parent=35239"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/product_cat?post=35239"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ati.novanta.com\/pt\/wp-json\/wp\/v2\/product_tag?post=35239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}